{"id":1922,"date":"2019-11-05T15:24:28","date_gmt":"2019-11-05T14:24:28","guid":{"rendered":"https:\/\/espace-chirurgie.ch\/?post_type=glossary&#038;p=1922"},"modified":"2019-11-05T15:24:29","modified_gmt":"2019-11-05T14:24:29","slug":"amnesie-absence-de-souvenir-decrochage-trous-de-memoire","status":"publish","type":"glossary","link":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/","title":{"rendered":"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Laps de temps sans souvenir. L&rsquo;amn\u00e9sie survient souvent suite \u00e0 des commotions c\u00e9r\u00e9brales, des \u00e9v\u00e8nements traumatisants ou une intoxication avec des drogues ou de l&rsquo;alcool.<\/p>\n","protected":false},"template":"","class_list":["post-1922","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie\" \/>\n<meta property=\"og:description\" content=\"Laps de temps sans souvenir. L&rsquo;amn\u00e9sie survient souvent suite \u00e0 des commotions c\u00e9r\u00e9brales, des \u00e9v\u00e8nements...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Espace Chirurgie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/espacechirurgie\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-05T14:24:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\\\/\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\\\/\",\"name\":\"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#website\"},\"datePublished\":\"2019-11-05T14:24:28+00:00\",\"dateModified\":\"2019-11-05T14:24:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\",\"name\":\"Espace Chirurgie\",\"description\":\"Zentrum mit modernster und qualitativ hochwertiger chirurgischer Behandlung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#organization\",\"name\":\"Espace Chirurgie\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/espace-chirurgie-logo.svg\",\"contentUrl\":\"https:\\\/\\\/espace-chirurgie.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/espace-chirurgie-logo.svg\",\"width\":403,\"height\":86,\"caption\":\"Espace Chirurgie\"},\"image\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espacechirurgie\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/espace-chirurgie\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie","og_description":"Laps de temps sans souvenir. L&rsquo;amn\u00e9sie survient souvent suite \u00e0 des commotions c\u00e9r\u00e9brales, des \u00e9v\u00e8nements...","og_url":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/","og_site_name":"Espace Chirurgie","article_publisher":"https:\/\/www.facebook.com\/espacechirurgie","article_modified_time":"2019-11-05T14:24:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/","url":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/","name":"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire) &#8211; Espace Chirurgie","isPartOf":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#website"},"datePublished":"2019-11-05T14:24:28+00:00","dateModified":"2019-11-05T14:24:29+00:00","breadcrumb":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/amnesie-absence-de-souvenir-decrochage-trous-de-memoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/espace-chirurgie.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Amn\u00e9sie (Absence de souvenir, d\u00e9crochage, trous de m\u00e9moire)"}]},{"@type":"WebSite","@id":"https:\/\/espace-chirurgie.ch\/fr\/#website","url":"https:\/\/espace-chirurgie.ch\/fr\/","name":"Espace Chirurgie","description":"Zentrum mit modernster und qualitativ hochwertiger chirurgischer Behandlung.","publisher":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espace-chirurgie.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/espace-chirurgie.ch\/fr\/#organization","name":"Espace Chirurgie","url":"https:\/\/espace-chirurgie.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/espace-chirurgie.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/espace-chirurgie.ch\/wp-content\/uploads\/2019\/06\/espace-chirurgie-logo.svg","contentUrl":"https:\/\/espace-chirurgie.ch\/wp-content\/uploads\/2019\/06\/espace-chirurgie-logo.svg","width":403,"height":86,"caption":"Espace Chirurgie"},"image":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espacechirurgie","https:\/\/www.linkedin.com\/company\/espace-chirurgie\/"]}]}},"_links":{"self":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/types\/glossary"}],"version-history":[{"count":1,"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1922\/revisions"}],"predecessor-version":[{"id":1928,"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1922\/revisions\/1928"}],"wp:attachment":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/media?parent=1922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}