{"id":1933,"date":"2019-11-05T15:27:25","date_gmt":"2019-11-05T14:27:25","guid":{"rendered":"https:\/\/espace-chirurgie.ch\/?post_type=glossary&#038;p=1933"},"modified":"2019-11-05T15:27:25","modified_gmt":"2019-11-05T14:27:25","slug":"alcalin-basique","status":"publish","type":"glossary","link":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/","title":{"rendered":"Alcalin (Basique)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Alcalin, solution aqueuse au pH \u00e9lev\u00e9<\/p>\n","protected":false},"template":"","class_list":["post-1933","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alcalin (Basique) &#8211; Espace Chirurgie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcalin (Basique) &#8211; Espace Chirurgie\" \/>\n<meta property=\"og:description\" content=\"Alcalin, solution aqueuse au pH \u00e9lev\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/\" \/>\n<meta property=\"og:site_name\" content=\"Espace Chirurgie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/espacechirurgie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/alcalin-basique\\\/\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/alcalin-basique\\\/\",\"name\":\"Alcalin (Basique) &#8211; Espace Chirurgie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#website\"},\"datePublished\":\"2019-11-05T14:27:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/alcalin-basique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/alcalin-basique\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/alcalin-basique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar\",\"item\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/glossaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alcalin (Basique)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\",\"name\":\"Espace Chirurgie\",\"description\":\"Zentrum mit modernster und qualitativ hochwertiger chirurgischer Behandlung.\",\"publisher\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#organization\",\"name\":\"Espace Chirurgie\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/espace-chirurgie.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/espace-chirurgie-logo.svg\",\"contentUrl\":\"https:\\\/\\\/espace-chirurgie.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/espace-chirurgie-logo.svg\",\"width\":403,\"height\":86,\"caption\":\"Espace Chirurgie\"},\"image\":{\"@id\":\"https:\\\/\\\/espace-chirurgie.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espacechirurgie\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/espace-chirurgie\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alcalin (Basique) &#8211; Espace Chirurgie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/","og_locale":"fr_FR","og_type":"article","og_title":"Alcalin (Basique) &#8211; Espace Chirurgie","og_description":"Alcalin, solution aqueuse au pH \u00e9lev\u00e9","og_url":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/","og_site_name":"Espace Chirurgie","article_publisher":"https:\/\/www.facebook.com\/espacechirurgie","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/","url":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/","name":"Alcalin (Basique) &#8211; Espace Chirurgie","isPartOf":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#website"},"datePublished":"2019-11-05T14:27:25+00:00","breadcrumb":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/alcalin-basique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/espace-chirurgie.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Glossar","item":"https:\/\/espace-chirurgie.ch\/fr\/glossaire\/"},{"@type":"ListItem","position":3,"name":"Alcalin (Basique)"}]},{"@type":"WebSite","@id":"https:\/\/espace-chirurgie.ch\/fr\/#website","url":"https:\/\/espace-chirurgie.ch\/fr\/","name":"Espace Chirurgie","description":"Zentrum mit modernster und qualitativ hochwertiger chirurgischer Behandlung.","publisher":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espace-chirurgie.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/espace-chirurgie.ch\/fr\/#organization","name":"Espace Chirurgie","url":"https:\/\/espace-chirurgie.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/espace-chirurgie.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/espace-chirurgie.ch\/wp-content\/uploads\/2019\/06\/espace-chirurgie-logo.svg","contentUrl":"https:\/\/espace-chirurgie.ch\/wp-content\/uploads\/2019\/06\/espace-chirurgie-logo.svg","width":403,"height":86,"caption":"Espace Chirurgie"},"image":{"@id":"https:\/\/espace-chirurgie.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espacechirurgie","https:\/\/www.linkedin.com\/company\/espace-chirurgie\/"]}]}},"_links":{"self":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/types\/glossary"}],"version-history":[{"count":1,"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1933\/revisions"}],"predecessor-version":[{"id":1941,"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/glossary\/1933\/revisions\/1941"}],"wp:attachment":[{"href":"https:\/\/espace-chirurgie.ch\/fr\/wp-json\/wp\/v2\/media?parent=1933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}